{"id":39,"count":4,"description":"","link":"https:\/\/test.carlosraul.dev\/en\/category\/casos-de-exito\/","name":"Case Studies","slug":"casos-de-exito","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/test.carlosraul.dev\/en\/wp-json\/wp\/v2\/categories\/39","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.carlosraul.dev\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/test.carlosraul.dev\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/test.carlosraul.dev\/en\/wp-json\/wp\/v2\/posts?categories=39"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}